{"id":251,"date":"2023-09-29T12:01:31","date_gmt":"2023-09-29T10:01:31","guid":{"rendered":"https:\/\/www.hockey.co.il\/?page_id=251"},"modified":"2024-09-06T17:33:46","modified_gmt":"2024-09-06T14:33:46","slug":"inline-roller-hockey-training-in-israel","status":"publish","type":"page","link":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/","title":{"rendered":"Inline\/roller hockey training in Israel"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-white-color has-text-color has-background has-link-color has-medium-font-size wp-elements-1\" style=\"background-color:#002cc1\">Upcoming roller hockey trainings<\/h2>\n\n\n<div class=\"eventer-dynamic-list-set\" id=\"eventer-dynamic-filters-744539\"><div id=\"eventer-dynamic-filters-area-121\" class=\"eventer eventer-dynamic-listings-main eventer-grid eventer-grid-clean eventer-grid-col3\"  data-shortcode=\"{&quot;ids&quot;:&quot;&quot;,&quot;terms_cats&quot;:&quot;495&quot;,&quot;terms_tags&quot;:&quot;459&quot;,&quot;terms_venue&quot;:&quot;&quot;,&quot;terms_organizer&quot;:&quot;&quot;,&quot;type&quot;:&quot;&quot;,&quot;status&quot;:&quot;future&quot;,&quot;lang&quot;:&quot;en&quot;,&quot;series&quot;:&quot;&quot;,&quot;layout&quot;:&quot;clean&quot;,&quot;background&quot;:&quot;&quot;,&quot;column&quot;:&quot;3&quot;,&quot;path&quot;:&quot;&quot;,&quot;venue&quot;:&quot;&quot;,&quot;filters&quot;:&quot;tag,venue&quot;,&quot;month_filter&quot;:&quot;1&quot;,&quot;name&quot;:&quot;eventer_grid&quot;,&quot;calview&quot;:&quot;monthly&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;operator&quot;:&quot;&quot;,&quot;ajax&quot;:&quot;&quot;,&quot;pass&quot;:&quot;&quot;,&quot;carousel&quot;:&quot;yes,3000,yes,yes,no&quot;,&quot;occurrence&quot;:&quot;&quot;,&quot;featured&quot;:&quot;&quot;,&quot;count&quot;:&quot;12&quot;,&quot;event_until&quot;:&quot;1&quot;,&quot;pagin&quot;:&quot;1&quot;}\"><div class=\"eventer-loader-wrap\" style=\"display:none\"><div class=\"eventer-loader\"><\/div><\/div><div class=\"eventer-month-switcher-wrap\"><div class=\"eventer-filter-wrap\"><label>Sort Events<\/label>\r\n        <div class=\"eventer-filter-col\">\r\n            <a class=\"eventer-filter-trigger eventer-btn eventer-btn-basic\" href=\"javascript:void(0)\">By Event Tags <i class=\"eventer-icon-arrow-down\"><\/i><\/a>\r\n            <ul class=\"eventer-filter-select \" data-taxonomy=\"terms_tags\">\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"457\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"457\"> 4 on 4<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"456\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"456\"> 5 on 5<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"465\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"465\"> adults<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"445\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"445\"> advanced<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"455\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"455\"> beginner<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"464\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"464\"> children<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"666\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"666\"> free<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"665\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"665\"> girls<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"458\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"458\"> ice hockey<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"459\" checked type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"459\"> inline-roller hockey<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"454\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"454\"> intermediate<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"463\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"463\"> juniors<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"664\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"664\"> skating<\/label>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/div>\r\n            <div class=\"eventer-filter-col\">\r\n            <a class=\"eventer-filter-trigger eventer-btn eventer-btn-basic\" href=\"javascript:void(0)\">By Event Venue <i class=\"eventer-icon-arrow-down\"><\/i><\/a>\r\n            <ul class=\"eventer-filter-select \" data-taxonomy=\"terms_venue\">\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"645\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"645\"> Beer Sheva roller rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1426\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1426\"> Blue Ice<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1347\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1347\"> Blue Ice Arena Ashdod<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"646\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"646\"> Haifa roller rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1432\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1432\"> Ice Peaks<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"639\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"639\"> Ice Peaks Holon<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1353\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1353\"> Jerusalem ON ICE rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1311\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1311\"> Matnas Berkovich Nof HaGalil<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1312\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1312\"> My Ice Rink in Yarka<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"642\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"642\"> Nes Ziona roller rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"641\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"641\"> One Ice Arena Small Rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"638\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"638\"> One Ice Arena Tnuvot<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1428\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1428\"> OneIce (big)<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"1429\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"1429\"> OneIce (small)<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"644\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"644\"> Petah Tikva roller rink<\/label>\r\n                    <\/li>\r\n                                    <li class=\"\">\r\n                        <label><input data-term=\"643\"  type=\"checkbox\" class=\"eventer-term-filters eventers-filter-check \" value=\"643\"> Rishon Le Tzion roller rink<\/label>\r\n                    <\/li>\r\n                            <\/ul>\r\n        <\/div>\r\n    <\/div>    <\/div><ul class=\"equah\"><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"803\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-300x241.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-768x617.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-600x482.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02&text=Event: Nes Ziona Club beginners inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02&title=Nes Ziona Club beginners inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club beginners inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-02\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club beginners inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 02-09-2026 17:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Wednesday, 17:00 to 18:15<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-300x200.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-768x512.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-600x400.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02&text=Event: Nes Ziona Club juniors inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02&title=Nes Ziona Club juniors inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club juniors inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-02\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club juniors inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 02-09-2026 18:15<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Wednesday, 18:15 to 19:30<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\" target=\"_self\"><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02&text=Event: Rishon Club roller\/inline hockey juniors training:https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02&title=Rishon Club roller\/inline hockey juniors training&source=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Rishon Club roller\/inline hockey juniors training&body=:https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-02\" target=\"_self\"><span class=\"eventer-event-title\">Rishon Club roller\/inline hockey juniors training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 02-09-2026 20:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Wednesday, 20:00 to 21:00<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"803\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-300x241.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-768x617.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-600x482.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06&text=Event: Nes Ziona Club beginners inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06&title=Nes Ziona Club beginners inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club beginners inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-06\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club beginners inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 06-09-2026 17:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Sunday, 17:00 to 18:15<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-300x200.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-768x512.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-600x400.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06&text=Event: Nes Ziona Club juniors inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06&title=Nes Ziona Club juniors inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club juniors inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-06\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club juniors inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 06-09-2026 18:15<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Sunday, 18:15 to 19:30<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\" target=\"_self\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/10\/haifa-kids-training-inline-roller.jpeg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/10\/haifa-kids-training-inline-roller.jpeg 1024w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/10\/haifa-kids-training-inline-roller-300x200.jpeg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/10\/haifa-kids-training-inline-roller-768x512.jpeg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/10\/haifa-kids-training-inline-roller-600x400.jpeg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06&text=Event: Haifa Club inline\/roller hockey juniors training:https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06&title=Haifa Club inline\/roller hockey juniors training&source=https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Haifa Club inline\/roller hockey juniors training&body=:https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/haifa-club-inline-roller-hockey-juniors-training\/edate\/2026-09-06\" target=\"_self\"><span class=\"eventer-event-title\">Haifa Club inline\/roller hockey juniors training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 06-09-2026 19:30<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Sunday, 19:30 to 20:30<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\" target=\"_self\"><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06&text=Event: Rishon Club roller\/inline hockey juniors training:https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06&title=Rishon Club roller\/inline hockey juniors training&source=https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Rishon Club roller\/inline hockey juniors training&body=:https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/rishon-club-roller-hockey-juniors-training\/edate\/2026-09-06\" target=\"_self\"><span class=\"eventer-event-title\">Rishon Club roller\/inline hockey juniors training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 06-09-2026 20:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Sunday, 20:00 to 21:00<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"803\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-300x241.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-768x617.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-600x482.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07&text=Event: Nes Ziona Club beginners inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07&title=Nes Ziona Club beginners inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club beginners inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-07\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club beginners inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 07-09-2026 17:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Monday, 17:00 to 18:15<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-300x200.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-768x512.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-600x400.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07&text=Event: Nes Ziona Club juniors inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07&title=Nes Ziona Club juniors inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club juniors inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-07\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club juniors inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 07-09-2026 18:15<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Monday, 18:15 to 19:30<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"803\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-300x241.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-768x617.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-600x482.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09&text=Event: Nes Ziona Club beginners inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09&title=Nes Ziona Club beginners inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club beginners inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-09\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club beginners inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 09-09-2026 17:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Wednesday, 17:00 to 18:15<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-300x200.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-768x512.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-max-600x400.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09&text=Event: Nes Ziona Club juniors inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09&title=Nes Ziona Club juniors inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club juniors inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-juniors-inline-roller-hockey-training\/edate\/2026-09-09\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club juniors inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 09-09-2026 18:15<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Wednesday, 18:15 to 19:30<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><li class=\"eventer-event-grid-item equah-item eventer-featured- new_eventer_status_\">\n\t<div class=\"eventer-grid-fimage\">\n\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\" target=\"_self\"><img decoding=\"async\" width=\"1000\" height=\"803\" src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/xstore\/xstore-placeholder.png\" class=\"attachment-full size-full lazyload lazyload-simple et-lazyload-fadeIn wp-post-image\" alt=\"\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-src=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg\" data-srcset=\"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team.jpg 1000w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-300x241.jpg 300w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-768x617.jpg 768w, https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/09\/club_nes-ziona_roller-team-600x482.jpg 600w\" \/><\/a>\n\t\t\t\t\t<div class=\"eventer-quick-share closed\">\n\t\t\t\t<a href=\"#\"><i class=\"eventer-icon-share\"><\/i><\/a>\n\t\t\t\t<ul>\n\t\t\t\t\t<li><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\"><i class=\"eventer-icon-social-facebook\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"https:\/\/twitter.com\/intent\/tweet?source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13&text=Event: Nes Ziona Club beginners inline\/roller hockey training:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\"><i class=\"eventer-icon-social-twitter\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13&title=Nes Ziona Club beginners inline\/roller hockey training&source=https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\"><i class=\"eventer-icon-social-linkedin\"><\/i><\/a><\/li>\n\t\t\t\t\t<li><a href=\"mailto:?subject=Nes Ziona Club beginners inline\/roller hockey training&body=:https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\"><i class=\"eventer-icon-envelope-letter\"><\/i><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<div class=\"eventer-grid-content\">\n\t\t<div class=\"eventer-event-title-wrap\">\n\t\t\t<div class=\"eventer-badges\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eventer-status-badge eventer-status-upcoming\"> Upcoming<\/span>\t\t\t<\/div>\n\t\t\t<a href=\"https:\/\/www.hockey.co.il\/en\/event\/nes-ziona-club-beginners-inline-roller-hockey-training\/edate\/2026-09-13\" target=\"_self\"><span class=\"eventer-event-title\">Nes Ziona Club beginners inline\/roller hockey training <\/span><\/a>\n\t\t<\/div>\n\t\t<div class=\"eventer-grid-meta\">\n\t\t\t<div><i class=\"eventer-icon-calendar\"><\/i> 13-09-2026 17:00<\/div>\n\t\t\t<div><i class=\"eventer-icon-clock\"><\/i> Sunday, 17:00 to 18:15<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n<\/li><\/ul><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-white-color has-text-color has-background has-link-color has-medium-font-size wp-elements-2\" style=\"background-color:#002cc1\">Roller hockey trainings calendar<\/h2>\n\n\n<div class=\"eventer-calendar-render\"><div data-calendar=\"c_901f3e7449a21f11ae8e3f08f509229efb74c4e8a679d24183d75e567076e9a3@group.calendar.google.com\" class=\"shortcode-vals\" style=\"display:none;\">{&quot;ids&quot;:&quot;&quot;,&quot;terms_cats&quot;:&quot;495&quot;,&quot;terms_tags&quot;:&quot;459&quot;,&quot;terms_venue&quot;:&quot;&quot;,&quot;terms_organizer&quot;:&quot;&quot;,&quot;type&quot;:&quot;&quot;,&quot;preview&quot;:&quot;&quot;,&quot;defaultDate&quot;:&quot;2026-09-02&quot;}<\/div><div class=\"calendar\"><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Upcoming roller hockey trainings Roller hockey trainings calendar<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":177,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-251","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.11 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Inline\/roller hockey training in Israel - \u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inline\/roller hockey training in Israel\" \/>\n<meta property=\"og:description\" content=\"Upcoming roller hockey trainings Roller hockey trainings calendar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/\" \/>\n<meta property=\"og:site_name\" content=\"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hockeycoil\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T14:33:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/inline-roller-hockey-training-in-israel\\\/\",\"url\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/inline-roller-hockey-training-in-israel\\\/\",\"name\":\"Inline\\\/roller hockey training in Israel - \u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#website\"},\"datePublished\":\"2023-09-29T10:01:31+00:00\",\"dateModified\":\"2024-09-06T14:33:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/inline-roller-hockey-training-in-israel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/inline-roller-hockey-training-in-israel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/inline-roller-hockey-training-in-israel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All hockey activities in Israel\",\"item\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"All roller\\\/inline hockey activities in Israel\",\"item\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/activities\\\/roller\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Inline\\\/roller hockey training in Israel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/\",\"name\":\"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc\",\"description\":\"Ice and inline hockey in Israel | \u05d4\u05d5\u05e7\u05d9 \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc - \u05d4\u05d5\u05e7\u05d9 \u05e8\u05d5\u05dc\u05e8 \u05d5\u05d4\u05d5\u05e7\u05d9 \u05e7\u05e8\u05d7\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#organization\",\"name\":\"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc\",\"url\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hockey.co.il\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo_hockey-il_750.png\",\"contentUrl\":\"https:\\\/\\\/www.hockey.co.il\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo_hockey-il_750.png\",\"width\":750,\"height\":150,\"caption\":\"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hockey.co.il\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hockeycoil\",\"https:\\\/\\\/www.instagram.com\\\/hockeycoil\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inline\/roller hockey training in Israel - \u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/","og_locale":"en_US","og_type":"article","og_title":"Inline\/roller hockey training in Israel","og_description":"Upcoming roller hockey trainings Roller hockey trainings calendar","og_url":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/","og_site_name":"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc","article_publisher":"https:\/\/www.facebook.com\/hockeycoil","article_modified_time":"2024-09-06T14:33:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/","url":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/","name":"Inline\/roller hockey training in Israel - \u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc","isPartOf":{"@id":"https:\/\/www.hockey.co.il\/en\/#website"},"datePublished":"2023-09-29T10:01:31+00:00","dateModified":"2024-09-06T14:33:46+00:00","breadcrumb":{"@id":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/inline-roller-hockey-training-in-israel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/www.hockey.co.il\/en\/"},{"@type":"ListItem","position":2,"name":"All hockey activities in Israel","item":"https:\/\/www.hockey.co.il\/en\/activities\/"},{"@type":"ListItem","position":3,"name":"All roller\/inline hockey activities in Israel","item":"https:\/\/www.hockey.co.il\/en\/activities\/roller\/"},{"@type":"ListItem","position":4,"name":"Inline\/roller hockey training in Israel"}]},{"@type":"WebSite","@id":"https:\/\/www.hockey.co.il\/en\/#website","url":"https:\/\/www.hockey.co.il\/en\/","name":"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc","description":"Ice and inline hockey in Israel | \u05d4\u05d5\u05e7\u05d9 \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc - \u05d4\u05d5\u05e7\u05d9 \u05e8\u05d5\u05dc\u05e8 \u05d5\u05d4\u05d5\u05e7\u05d9 \u05e7\u05e8\u05d7","publisher":{"@id":"https:\/\/www.hockey.co.il\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hockey.co.il\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hockey.co.il\/en\/#organization","name":"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc","url":"https:\/\/www.hockey.co.il\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hockey.co.il\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/11\/logo_hockey-il_750.png","contentUrl":"https:\/\/www.hockey.co.il\/wp-content\/uploads\/2023\/11\/logo_hockey-il_750.png","width":750,"height":150,"caption":"\u05d4\u05d5\u05e7\u05d9 \u05d9\u05e9\u05e8\u05d0\u05dc"},"image":{"@id":"https:\/\/www.hockey.co.il\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hockeycoil","https:\/\/www.instagram.com\/hockeycoil"]}]}},"_links":{"self":[{"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/pages\/251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/comments?post=251"}],"version-history":[{"count":0,"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/pages\/251\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/pages\/177"}],"wp:attachment":[{"href":"https:\/\/www.hockey.co.il\/en\/wp-json\/wp\/v2\/media?parent=251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}